{"id":2954,"date":"2024-09-24T18:05:40","date_gmt":"2024-09-24T16:05:40","guid":{"rendered":"https:\/\/sunuentreprise.sn\/?p=2954"},"modified":"2024-09-24T18:05:40","modified_gmt":"2024-09-24T16:05:40","slug":"autonomisation-des-pmela-directrice-de-lequite-sociale-apporte-son-appui-a-ziguinchor","status":"publish","type":"post","link":"https:\/\/sunuentreprise.sn\/index.php\/2024\/09\/24\/autonomisation-des-pmela-directrice-de-lequite-sociale-apporte-son-appui-a-ziguinchor\/","title":{"rendered":"AUTONOMISATION DES PME:La directrice de l&rsquo;\u00e9quit\u00e9 sociale apporte son appui \u00e0 Ziguinchor"},"content":{"rendered":"\n<p>La directrice de l\u2019\u00e9quit\u00e9 sociale au minist\u00e8re de la Famille et des Solidarit\u00e9s, Fatoumata Bintou Di\u00e9dhiou a lanc\u00e9 vendredi 20 septembre 2024, un appel aux jeunes de S\u00e9dhiou lors d\u2019une rencontre d\u2019information et de sensibilisation sur les nouvelles d\u00e9marches de financement des petites et moyennes entreprises (PME). Mme Di\u00e9dhiou demande \u00e0 la jeunesse de rester dans leurs terroirs, afin de devenir des acteurs cl\u00e9s de leur d\u00e9veloppement \u00e9conomique et social.<\/p>\n\n\n\n<p>A travers cet appel, Mme Di\u00e9dhiou entend soutenir les nouvelles initiatives du gouvernement sous la direction du pr\u00e9sident de la R\u00e9publique, Bassirou Diomaye Diakhar Faye, tout en rappelant que les jeunes et les femmes sont le moteur du d\u00e9veloppement du pays. La coordonnatrice de la zone sud de \u201dDjigu\u00e9nou Pastef\u201d a r\u00e9v\u00e9l\u00e9 que le minist\u00e8re de la Famille et des Solidarit\u00e9s a mis en place un ensemble de programmes visant \u00e0 soutenir l\u2019autonomisation des petites et moyennes entreprises (PME).<br>D&rsquo;apr\u00e8s Fatoumata Bintou Di\u00e9dhiou, soutenir l\u2019autonomisation des petites et moyennes entreprises (PME) est important pour le d\u00e9veloppement \u00e9conomique local.<br>D\u2019ailleurs \u00e0 Ziguinchor, les op\u00e9rations de financement ont d\u00e9marr\u00e9 ce lundi 23 septembre, avec un encadrement rigoureux et un suivi continu des projets.<br>La directrice de l&rsquo;\u00e9quit\u00e9 sociale signale qu&rsquo;en identifiant et en soutenant les entrepreneurs et les Pme, le gouvernement va stimuler une croissance durable et inclusive par le biais de sa direction qui va travailler sans rel\u00e2che pour concr\u00e9tiser la vision politique du gouvernement en mati\u00e8re d\u2019\u00e9quit\u00e9 sociale et territoriale dans tous les secteurs d\u2019activit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La directrice de l\u2019\u00e9quit\u00e9 sociale au minist\u00e8re de la<\/p>\n","protected":false},"author":1,"featured_media":2955,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,53,4],"tags":[41,328,329,32,201],"class_list":["post-2954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualites","category-pme-pmi","tag-appui","tag-autonomisation","tag-directrice-de-lequite-sociale","tag-pme","tag-ziguinchor"],"_links":{"self":[{"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/posts\/2954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/comments?post=2954"}],"version-history":[{"count":1,"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/posts\/2954\/revisions"}],"predecessor-version":[{"id":2956,"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/posts\/2954\/revisions\/2956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/media\/2955"}],"wp:attachment":[{"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/media?parent=2954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/categories?post=2954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sunuentreprise.sn\/index.php\/wp-json\/wp\/v2\/tags?post=2954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}